{"id":2795,"date":"2014-04-03T10:02:14","date_gmt":"2014-04-03T16:02:14","guid":{"rendered":"http:\/\/catolicasmexico.com\/blog\/?p=2795"},"modified":"2014-04-03T10:02:14","modified_gmt":"2014-04-03T16:02:14","slug":"un-empleado-de-starbucks-dibuja-simbolos-satanicos-en-el-cafe-de-unas-clientas-catolicas-rel","status":"publish","type":"post","link":"https:\/\/catolicasmexico.com\/blog\/un-empleado-de-starbucks-dibuja-simbolos-satanicos-en-el-cafe-de-unas-clientas-catolicas-rel\/","title":{"rendered":"Un empleado de Starbucks dibuja s\u00edmbolos sat\u00e1nicos en el caf\u00e9 de unas clientas cat\u00f3licas &#8211; ReL"},"content":{"rendered":"<p><a href=\"http:\/\/catolicasmexico.com\/blog\/wp-content\/uploads\/2014\/04\/20140403-121337.jpg\"><img src=\"http:\/\/catolicasmexico.com\/blog\/wp-content\/uploads\/2014\/04\/20140403-121337.jpg\" alt=\"20140403-121337.jpg\" class=\"alignnone size-full\"  \/> <\/a><\/p>\n<p>Articulo de Religi\u00f3n en libertad.<br \/>\nDos maestras cat\u00f3licas mostraron su indignaci\u00f3n despu\u00e9s de que un empleado de la cadena de caf\u00e9 Starbuck dibujara dos s\u00edmbolos sat\u00e1nicos en la crema de los lattes que hab\u00edan solicitado.<\/p>\n<p>El domingo, despu\u00e9s de recibir sus caf\u00e9 en el Starbuck ubicado dentro del centro comercial Mall of Louisiana en Baton Rouge, Megan K.Pi\u00f1on public\u00f3 una fotograf\u00eda en su cuenta de Facebook donde mostr\u00f3 un latte con un pent\u00e1culo o estrella de 5 puntas dibujado con jarabe de caramelo y en otro el n\u00famero \u00ab666\u00bb.<\/p>\n<p>\u00abLamentablemente, yo no puedo dar el nombre del joven que lo sirvi\u00f3, porque estaba tan horrorizada que no me atrev\u00eda a mirarlo\u00bb, escribi\u00f3 Pi\u00f1on al pie de la foto.<\/p>\n<p>(&#8230;)<\/p>\n<p>Despu\u00e9s de que la imagen fuera colgada en redes sociales, la cadena de caf\u00e9 se vio obligada a emitir un mensaje en el que disculp\u00f3 con Pi\u00f1on. \u00abEstamos tomando la queja en serio y hemos pedido disculpas sinceramente por su experiencia\u00bb, indic\u00f3 el portavoz de Starbuck, Tom Kuhn.<\/p>\n<p>\u00abEste no es el tipo de experiencia que queremos ofrecer a nuestros clientes y no es representativa de la atenci\u00f3n al cliente que nuestros socios proporcionan a millones de clientes todos los d\u00edas\u00bb, asegur\u00f3 \u00bb Tom Kuhn a The Huffington Post.<\/p>\n<p>Tom Kuhn se neg\u00f3 a revelar el nombre del empleado en Luisiana y las medidas que la empresa tomar\u00eda en reacci\u00f3n a sus actos, asegurando que una de sus pol\u00edticas internas es no hablar de los detalles sobre el empleo de su personal.<\/p>\n<p>Starbucks, multinacional anti-familia<br \/>\nM\u00e1s all\u00e1 de la an\u00e9cdota de que un trabajador de Starbucks busque escandalizar con signos sat\u00e1nicos, el caso es que la poderosa multinacional del caf\u00e9 de lujo desde enero de 2012 es oficialmente militante en la redefinici\u00f3n del matrimonio para que deje de ser la uni\u00f3n entre un hombre y una mujer. <\/p>\n<p>Starbucks dedic\u00f3 un importante donativo a apoyar la campa\u00f1a del lobby gay que redefini\u00f3 el matrimonio en el estado de Washington y mand\u00f3 cartas a sus socios apoyando la doctrina LGBT en esta campa\u00f1a. <\/p>\n<p>Desde entonces, las asociaciones profamilia han pedido \u00aba quien valore la familia\u00bb que no consuma en Starbucks. <\/p>\n<p>Al parecer, las profesoras cat\u00f3licas de Baton Rouge no conoc\u00edan o no valoraban el car\u00e1cter anti-familia de la poderosa multinacional.<\/p>\n<p>Recientemente, un accionista de Starbucks pidi\u00f3 a los directivos que reconsiderasen su militancia en la ideolog\u00eda del homosexualismo pol\u00edtico (ReL lo explic\u00f3 aqu\u00ed). Se le respondi\u00f3: \u00abvenda sus acciones de Starbucks y c\u00f3mprelas de otra compa\u00f1\u00eda\u00bb, o dicho de otra forma, el compromiso ideol\u00f3gico de Starbucks contra la familia de ra\u00edz judeocristiana es firme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articulo de Religi\u00f3n en libertad. Dos maestras cat\u00f3licas mostraron su indignaci\u00f3n despu\u00e9s de que un empleado de la cadena de caf\u00e9 Starbuck dibujara dos s\u00edmbolos sat\u00e1nicos en la crema de los lattes que hab\u00edan solicitado. El domingo, despu\u00e9s de recibir sus caf\u00e9 en el Starbuck ubicado dentro del centro comercial Mall of Louisiana en Baton [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[335,72],"tags":[369,276,368],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/catolicasmexico.com\/blog\/wp-content\/uploads\/2014\/04\/20140403-121337.jpg","jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p3B5XH-J5","jetpack-related-posts":[{"id":3038,"url":"https:\/\/catolicasmexico.com\/blog\/los-grupos-de-rock-satanicos\/","url_meta":{"origin":2795,"position":0},"title":"Los grupos de rock sat\u00e1nicos.","date":"12 junio 2014","format":false,"excerpt":"(...) El grupo Mayhem fundado por su guitarrista Aarseth en 1983 con s\u00f3lo quince a\u00f1os de edad se maquillaba macabramente se centra cada vez m\u00e1s en el satanismo y todo lo que es algo morboso y blasfemo. Adopt\u00f3 el seudonimo de \"Euronymous\" el cual aparece en la Biblia sat\u00e1nica de\u2026","rel":"","context":"En \u00abataques contra la Iglesia Catolica\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3680,"url":"https:\/\/catolicasmexico.com\/blog\/deje-mi-trabajo-en-la-clinica-de-aborto-despues-de-asistir-al-aborto-de-cuatrillizos-perfectamente-formados-el-testimonio-de-un-ex-empleado\/","url_meta":{"origin":2795,"position":1},"title":"\"Dej\u00e9 mi trabajo en la cl\u00ednica de aborto despu\u00e9s de asistir al aborto de cuatrillizos  perfectamente formados\". El testimonio de un ex empleado.","date":"20 marzo 2015","format":false,"excerpt":"...\"estos dos beb\u00e9s totalmente formados estaban abrazados\" Por Ben Johnson con aporte de Dustin Siggins de LifeSiteNews del sitio del CQV traducci\u00f3n y edici\u00f3n libre CM (...)El mensaje entero a Johnson: Una mujer vino a nuestra cl\u00ednica una tarde, retorci\u00e9ndose de dolor. Otra cl\u00ednica de aborto le hab\u00eda dado una\u2026","rel":"","context":"En \u00abAborto\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3979,"url":"https:\/\/catolicasmexico.com\/blog\/ritual-satanico-en-el-exterior-de-planned-parenthood\/","url_meta":{"origin":2795,"position":2},"title":"Ritual Sat\u00e1nico en el exterior de Planned Parenthood.","date":"26 agosto 2015","format":false,"excerpt":"\"En algunas escrituras ocultas, una relaci\u00f3n y ritual se hace utilizando leche como s\u00edmbolo de una madre lactante y la leche de ba\u00f1o como un signo de adoraci\u00f3n a la diosa madre tierra (Gaia).\" DETROIT, 22 de agosto de 2015 (ChurchMilitant.com) \u00a0traducci\u00f3n CM- Al mismo tiempo que unos manifestantes se\u2026","rel":"","context":"En \u00abAborto\u00bb","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/catolicasmexico.com\/blog\/wp-content\/uploads\/2015\/08\/Screenshot_2015-08-22_at_3.24.03_PM.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2038,"url":"https:\/\/catolicasmexico.com\/blog\/una-aberracion-mas-prestaciones-de-maternidad-para-las-madres-que-abortan\/","url_meta":{"origin":2795,"position":3},"title":"Una aberraci\u00f3n m\u00e1s: Prestaciones de maternidad para las madres que abortan...","date":"7 noviembre 2013","format":false,"excerpt":"Del sitio de www.cqv.cq.ca traducci\u00f3n , edici\u00f3n y comentario www.catolicasmexico.com He aqu\u00ed el colmo del descaro: en Qu\u00e9bec,Canad\u00e1, se otorga a las madres que deciden eliminar a sus hijos vacaciones pagadas... La ley estable que: (...) Ambos padres pueden estar ausentes del trabajo durante cinco d\u00edas despu\u00e9s de una interrupci\u00f3n\u2026","rel":"","context":"En \u00abAborto\u00bb","img":{"alt_text":"","src":"https:\/\/i1.wp.com\/catolicasmexico.com\/blog\/wp-content\/uploads\/2013\/11\/20131107-1838131.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3631,"url":"https:\/\/catolicasmexico.com\/blog\/eliminar-las-fiestas-catolicas-ley-macron-iniciativa-por-una-legislacion-contra-la-sociedad-la-familia-y-la-cristiandad\/","url_meta":{"origin":2795,"position":4},"title":"Eliminar las fiestas cat\u00f3licas: Ley Macron, iniciativa por una legislaci\u00f3n contra la sociedad,  la familia y la cristiandad.","date":"5 marzo 2015","format":false,"excerpt":"\u00a0 Fuente\u00a0Traducci\u00f3n para catolicasmexico.com Para evitar un rechazo casi garantizado de la ley delante de la Asamblea Nacional, el gobierno recurri\u00f3 al art\u00edculo 49.3 de la Constituci\u00f3n. El Gobierno Holanda-Valls sobrevive solamente por la fuerza. \u00a0 Tengamos en cuenta que dentro del UMP, gente como Thierry Mariani y Herv\u00e9 Mariton,\u2026","rel":"","context":"En \u00abataques contra la Iglesia Catolica\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/catolicasmexico.com\/blog\/wp-content\/uploads\/2015\/03\/macron_emmanuel1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2079,"url":"https:\/\/catolicasmexico.com\/blog\/prohiben-a-una-periodista-noruega-llevar-una-cruz-en-el-cuello\/","url_meta":{"origin":2795,"position":5},"title":"Proh\u00edben a una periodista noruega llevar una cruz en el cuello","date":"18 noviembre 2013","format":false,"excerpt":"Del ForumLibertas.com Una cadena de oro con una peque\u00f1a cruz de piedras oscuras causa ofensa al Islam. Un s\u00edmbolo religioso apareci\u00f3 durante la realizaci\u00f3n de un telediario en el cuello de una conocida periodista de la televisi\u00f3n NRK, que ha enfurecido a colectivos musulmanes. Sucedi\u00f3 en Noruega. La protagonista de\u2026","rel":"","context":"En \u00abLibertad de expresi\u00f3n\u00bb","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/catolicasmexico.com\/blog\/wp-content\/uploads\/2013\/11\/20131118-1721062.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/posts\/2795"}],"collection":[{"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/comments?post=2795"}],"version-history":[{"count":1,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/posts\/2795\/revisions"}],"predecessor-version":[{"id":2796,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/posts\/2795\/revisions\/2796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/media\/2794"}],"wp:attachment":[{"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/media?parent=2795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/categories?post=2795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catolicasmexico.com\/blog\/wp-json\/wp\/v2\/tags?post=2795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}